<br />
<b>Warning</b>:  Attempt to read property "form_key" on null in <b>/home/zuttch/public_html/sites/www.zutt.ch/blog/wp-content/plugins/visual-form-builder/public/class-form-display.php</b> on line <b>234</b><br />
<br />
<b>Warning</b>:  Attempt to read property "form_id" on null in <b>/home/zuttch/public_html/sites/www.zutt.ch/blog/wp-content/plugins/visual-form-builder/public/class-form-display.php</b> on line <b>238</b><br />
{"id":8321,"date":"2020-06-08T14:00:49","date_gmt":"2020-06-08T14:00:49","guid":{"rendered":"https:\/\/zutt.ch\/?p=8321"},"modified":"2020-09-17T12:13:07","modified_gmt":"2020-09-17T12:13:07","slug":"neurobranches","status":"publish","type":"post","link":"https:\/\/zutt.ch\/blog\/de\/neurobranches\/","title":{"rendered":"NeuroBranches"},"content":{"rendered":"<h1 class=\"fliesstext\">Neuromarketing in der Praxis<\/h1>\n<h2>Wie physische R\u00e4ume im digitalen Zeitalter gewinnbringend genutzt werden k\u00f6nnen.<\/h2>\n<p>Mit dem Einzug der Digitalisierung hat sich ein grosser Teil der Gesch\u00e4ftsabschl\u00fcsse in den digitalen Raum verlagert. Es besteht f\u00fcr den Kunden oft keine absolute Notwenigkeit mehr, f\u00fcr einen Kauf den Weg in eine Filiale auf sich zu nehmen. Doch physische R\u00e4ume und Kontakte bieten gerade f\u00fcr die Kundenbindung und Differenzierung entscheidende Vorteile. Durch das gekonnte Ansprechen aller f\u00fcnf Sinne k\u00f6nnen emotional sehr starke Erlebnisse geschaffen werden. Ausserdem bieten POS eine Chance auf ein knappes Gut: Echten pers\u00f6nlichen Kontakt.<\/p>\n<hr \/>\n<p>Inhalts-\u00dcbersicht:<br \/>\n<strong><a href=\"#raiffeisen-case\">1. Raiffeisen Filiale &gt;<\/a><\/strong><br \/>\n<strong><a href=\"#topshop-case\">2. AGROLA TopShop &gt;<\/a><\/strong><br \/>\n<strong><a href=\"#workshop\">3. Emotionalisieren auch Sie Ihre Kundenfl\u00e4che &gt;<\/a><\/strong><\/p>\n<hr \/>\n<p id=\"raiffeisen-case\" class=\"h2\" style=\"margin-top: 60px;\">Case 1: Raiffeisen Filiale<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5894\" src=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/04\/zutt-neuromarketing-Wert3.svg\" alt=\"zutt-neuromarketing-Anspruch\" width=\"99\" height=\"153\" \/><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #187477;\">1. ANSPRUCH<\/span><strong><br \/>\n<\/strong><\/strong>Die Raiffeisenbank, Bankthemen und Banker auf Augenh\u00f6he mit dem Kunden bringen \u2013\u00a0durch neue, noch nie in der Bankwelt gesehene Rituale und Emotionalit\u00e4ten.<\/p>\n<p style=\"margin-top: 75px;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5894\" src=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/04\/zutt-neuromarketing-Wert1.svg\" alt=\"zutt-neuromarketing-Insights\" width=\"99\" height=\"153\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #187477;\"><strong>2. INSIGHTS EMOCOMPASS\u00ae-STUDIE<\/strong><\/span><br \/>\n\u2022 At Home Feeling bildet den emotional auszuspielenden Kern<br \/>\n\u2022 Innovation-Hub hingegen passt nicht zu den Wunsch-Emotionen<br \/>\n\u2022 Learning trifft hingegen das emotionale Soll \u2013 wenn durch einen pers\u00f6nlichen Touch aufgeladen<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5841 size-full\" src=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2019\/04\/zutt-neuromarketing-emomap-raiffeisen.png\" alt=\"zutt-neuromarketing-emomap-raiffeisen\" width=\"1024\" height=\"546\" \/><\/p>\n<p style=\"margin-top: -25px;\"><span style=\"color: #187477; font-size: 10pt; line-height: 0;\">EmoMap\u00a9: Es geht nicht um oben, unten, links oder rechts \u2013 massgebend sind die Abst\u00e4nde zwischen den einzelnen Research Objects zum Wunsch (GOLD STANDARD). Je weiter die Entfernung zwischen zwei Pins, desto unterschiedlicher die Empfindung.<\/span><\/p>\n<p style=\"margin-top: 75px;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5894\" src=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/04\/zutt-neuromarketing-Wert2.svg\" alt=\"zutt-neuromarketing-Erfolg\" width=\"99\" height=\"153\" \/><br \/>\n<strong><span style=\"color: #187477;\">3. ERFOLGSWIRKSAM EMOTIONALISIERTE RAIFFEISENBANK THALWIL<\/span><\/strong><br \/>\n\u2022 5 Minuten vor dem vereinbarten Beratungstermin: Der Kundenberater wartet (am Notebook arbeitend) in der Kundenzone am hohen Desk auf den Kunden<br \/>\n\u2022 Am grossen Screen &#8222;fliegen&#8220; Kunde und Berater \u00fcber das eigene Marktgebiet und entdecken gemeinsam vielleicht sogar das eigene Haus \/ die eigene Wohnung des Kunden<br \/>\n\u2022 An der Bar bereitet der Kundenberater selbst den Kaffee, Cappuccino oder Tee f\u00fcr den Kunden zu (nicht der Assistent \/ die Assistentin!)<br \/>\n\u2022 Das sind alles neu geschaffene Rituale f\u00fcr ein \u00fcberraschendes Kundenerlebnis auf Augenh\u00f6he<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-5894\" src=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2020\/09\/zutt-neuromarketing-raiffeisen-filiale-thalwil.png\" alt=\"Case Bild einer Raiffeisen Filiale\" \/><\/p>\n<hr \/>\n<p id=\"topshop-case\" class=\"h2\" style=\"margin-top: 60px;\">Case 2: AGROLA TopShop<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5894\" src=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/04\/zutt-neuromarketing-Wert3.svg\" alt=\"zutt-neuromarketing-Anspruch\" width=\"99\" height=\"153\" \/><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #187477;\">1. ANSPRUCH<\/span><strong><br \/>\n<\/strong><\/strong>Die Tankstellenshops von AGROLA richtig emotionalisieren und ihnen zu mehr Umsatz verhelfen.<\/p>\n<p style=\"margin-top: 75px;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5894\" src=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/04\/zutt-neuromarketing-Wert1.svg\" alt=\"zutt-neuromarketing-Insights\" width=\"99\" height=\"153\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #187477;\"><strong>2. INSIGHTS EMOCOMPASS\u00ae-STUDIE<\/strong><\/span><br \/>\n\u2022 Esswaren sind zentral<br \/>\n\u2022 B\u00e4ckerei und Kaffee sind Wunsch-Gastro-Angebote<br \/>\n\u2022 Regionaler Bezug und l\u00e4ndliche Attribute spielen eine grosse Rolle<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5841 size-full\" src=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2019\/04\/zutt-neuromarketing-emomap-topshop.png\" alt=\"zutt-neuromarketing-emomap-topshop\" width=\"1024\" height=\"546\" \/><\/p>\n<p style=\"margin-top: -25px;\"><span style=\"color: #187477; font-size: 10pt; line-height: 0;\">EmoMap\u00a9: Es geht nicht um oben, unten, links oder rechts \u2013 massgebend sind die Abst\u00e4nde zwischen den einzelnen Research Objects zum Wunsch (GOLD STANDARD). Je weiter die Entfernung zwischen zwei Pins, desto unterschiedlicher die Empfindung.<\/span><\/p>\n<p style=\"margin-top: 75px;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5894\" src=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/04\/zutt-neuromarketing-Wert2.svg\" alt=\"zutt-neuromarketing-Erfolg\" width=\"99\" height=\"153\" \/><br \/>\n<strong><span style=\"color: #187477;\">3. ERFOLGSWIRKSAM EMOTIONALISIERTE TOPSHOP-L\u00c4DEN<\/span><\/strong><br \/>\nVer\u00e4nderung Ladenlook, Ladenlayout, Eigenmarkenlinie und Rituale basierend auf Konzept-Inputs von ZUTT &amp; PARTNER<\/p>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-5894\" src=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2019\/10\/zutt-neuromarketing-topshop-vorher-nachher.png\" alt=\"Case Bild einer Topshop Filiale\" \/><\/p>\n<hr \/>\n<p id=\"workshop\" class=\"h2\">Emotionalisieren auch Sie Ihre Kundenfl\u00e4che<\/p>\n<h3>Jetzt anmelden f\u00fcr einen kostenlosen Workshop<\/h3>\n<p>Im Rahmen eines Gratis-Workshops* definieren wir gemeinsam, welche Gold Standards f\u00fcr Ihre Marke zu erforschen sind. Erleben Sie den EmoCompass\u00ae mit einer auf Sie zugeschnittenen Demo-Befragung und konfigurieren Sie Ihr EmoCompass\u00ae-Projekt, so dass Sie Ihre Marketingziele mit Einbezug neuropsychologischer Prinzipien wissenschaftlich erreichen.<\/p>\n<div id=\"vfb-form-6\" class=\"visual-form-builder-container\"><form id=\"-6\" class=\"visual-form-builder vfb-form-6 \" method=\"post\" enctype=\"multipart\/form-data\">\n\t  \t<input type=\"hidden\" name=\"form_id\" value=\"0\" \/><fieldset class=\"vfb-fieldset\"><div class=\"vfb-legend\" style=\"background-color:#FFEBE8;border:1px solid #CC0000;\"><h3>Oops! Missing Fieldset<\/h3><p style=\"color:black;\">If you are seeing this message, it means you need to &lt;strong&gt;add a Fieldset to the beginning of your form&lt;\/strong&gt;. Your form may not function or display properly without one.<\/p><\/div><ul class=\"section section-1\"><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1300\"><label for=\"vfb-1300\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1300\" id=\"vfb-1300\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1200\"><label for=\"vfb-1200\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1200\" id=\"vfb-1200\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1301\"><label for=\"vfb-1301\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1301\" id=\"vfb-1301\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1201\"><label for=\"vfb-1201\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1201\" id=\"vfb-1201\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1302\"><label for=\"vfb-1302\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1302\" id=\"vfb-1302\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1202\"><label for=\"vfb-1202\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1202\" id=\"vfb-1202\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1303\"><label for=\"vfb-1303\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1303\" id=\"vfb-1303\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1203\"><label for=\"vfb-1203\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1203\" id=\"vfb-1203\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1304\"><label for=\"vfb-1304\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1304\" id=\"vfb-1304\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1204\"><label for=\"vfb-1204\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1204\" id=\"vfb-1204\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1305\"><label for=\"vfb-1305\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1305\" id=\"vfb-1305\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1205\"><label for=\"vfb-1205\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1205\" id=\"vfb-1205\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1306\"><label for=\"vfb-1306\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1306\" id=\"vfb-1306\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1206\"><label for=\"vfb-1206\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1206\" id=\"vfb-1206\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1307\"><label for=\"vfb-1307\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1307\" id=\"vfb-1307\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1207\"><label for=\"vfb-1207\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1207\" id=\"vfb-1207\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1308\"><label for=\"vfb-1308\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1308\" id=\"vfb-1308\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1208\"><label for=\"vfb-1208\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1208\" id=\"vfb-1208\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1309\"><label for=\"vfb-1309\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1309\" id=\"vfb-1309\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1209\"><label for=\"vfb-1209\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1209\" id=\"vfb-1209\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1310\"><label for=\"vfb-1310\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1310\" id=\"vfb-1310\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1210\"><label for=\"vfb-1210\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1210\" id=\"vfb-1210\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1311\"><label for=\"vfb-1311\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1311\" id=\"vfb-1311\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1211\"><label for=\"vfb-1211\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1211\" id=\"vfb-1211\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1312\"><label for=\"vfb-1312\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1312\" id=\"vfb-1312\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1212\"><label for=\"vfb-1212\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1212\" id=\"vfb-1212\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1313\"><label for=\"vfb-1313\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1313\" id=\"vfb-1313\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1213\"><label for=\"vfb-1213\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1213\" id=\"vfb-1213\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1314\"><label for=\"vfb-1314\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1314\" id=\"vfb-1314\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1214\"><label for=\"vfb-1214\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1214\" id=\"vfb-1214\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1315\"><label for=\"vfb-1315\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1315\" id=\"vfb-1315\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1215\"><label for=\"vfb-1215\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1215\" id=\"vfb-1215\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1316\"><label for=\"vfb-1316\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1316\" id=\"vfb-1316\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1216\"><label for=\"vfb-1216\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1216\" id=\"vfb-1216\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1317\"><label for=\"vfb-1317\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1317\" id=\"vfb-1317\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1217\"><label for=\"vfb-1217\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1217\" id=\"vfb-1217\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1318\"><label for=\"vfb-1318\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1318\" id=\"vfb-1318\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1218\"><label for=\"vfb-1218\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1218\" id=\"vfb-1218\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1319\"><label for=\"vfb-1319\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1319\" id=\"vfb-1319\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1219\"><label for=\"vfb-1219\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1219\" id=\"vfb-1219\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1320\"><label for=\"vfb-1320\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1320\" id=\"vfb-1320\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1220\"><label for=\"vfb-1220\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1220\" id=\"vfb-1220\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1321\"><label for=\"vfb-1321\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1321\" id=\"vfb-1321\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1221\"><label for=\"vfb-1221\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1221\" id=\"vfb-1221\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1322\"><label for=\"vfb-1322\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1322\" id=\"vfb-1322\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1222\"><label for=\"vfb-1222\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1222\" id=\"vfb-1222\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1323\"><label for=\"vfb-1323\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1323\" id=\"vfb-1323\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1223\"><label for=\"vfb-1223\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1223\" id=\"vfb-1223\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1324\"><label for=\"vfb-1324\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1324\" id=\"vfb-1324\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1224\"><label for=\"vfb-1224\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1224\" id=\"vfb-1224\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1325\"><label for=\"vfb-1325\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1325\" id=\"vfb-1325\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1225\"><label for=\"vfb-1225\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1225\" id=\"vfb-1225\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1326\"><label for=\"vfb-1326\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1326\" id=\"vfb-1326\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1226\"><label for=\"vfb-1226\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1226\" id=\"vfb-1226\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1327\"><label for=\"vfb-1327\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1327\" id=\"vfb-1327\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1227\"><label for=\"vfb-1227\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1227\" id=\"vfb-1227\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1328\"><label for=\"vfb-1328\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1328\" id=\"vfb-1328\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1228\"><label for=\"vfb-1228\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1228\" id=\"vfb-1228\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1329\"><label for=\"vfb-1329\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1329\" id=\"vfb-1329\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1229\"><label for=\"vfb-1229\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1229\" id=\"vfb-1229\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1330\"><label for=\"vfb-1330\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1330\" id=\"vfb-1330\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1230\"><label for=\"vfb-1230\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1230\" id=\"vfb-1230\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1331\"><label for=\"vfb-1331\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1331\" id=\"vfb-1331\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1231\"><label for=\"vfb-1231\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1231\" id=\"vfb-1231\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1332\"><label for=\"vfb-1332\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1332\" id=\"vfb-1332\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1232\"><label for=\"vfb-1232\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1232\" id=\"vfb-1232\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1333\"><label for=\"vfb-1333\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1333\" id=\"vfb-1333\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1233\"><label for=\"vfb-1233\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1233\" id=\"vfb-1233\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1334\"><label for=\"vfb-1334\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1334\" id=\"vfb-1334\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1234\"><label for=\"vfb-1234\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1234\" id=\"vfb-1234\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1335\"><label for=\"vfb-1335\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1335\" id=\"vfb-1335\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1235\"><label for=\"vfb-1235\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1235\" id=\"vfb-1235\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1336\"><label for=\"vfb-1336\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1336\" id=\"vfb-1336\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1236\"><label for=\"vfb-1236\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1236\" id=\"vfb-1236\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1337\"><label for=\"vfb-1337\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1337\" id=\"vfb-1337\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1237\"><label for=\"vfb-1237\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1237\" id=\"vfb-1237\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1338\"><label for=\"vfb-1338\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1338\" id=\"vfb-1338\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1238\"><label for=\"vfb-1238\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1238\" id=\"vfb-1238\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1339\"><label for=\"vfb-1339\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1339\" id=\"vfb-1339\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1239\"><label for=\"vfb-1239\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1239\" id=\"vfb-1239\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1340\"><label for=\"vfb-1340\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1340\" id=\"vfb-1340\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1240\"><label for=\"vfb-1240\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1240\" id=\"vfb-1240\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1341\"><label for=\"vfb-1341\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1341\" id=\"vfb-1341\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1241\"><label for=\"vfb-1241\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1241\" id=\"vfb-1241\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1342\"><label for=\"vfb-1342\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1342\" id=\"vfb-1342\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1242\"><label for=\"vfb-1242\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1242\" id=\"vfb-1242\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1343\"><label for=\"vfb-1343\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1343\" id=\"vfb-1343\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1243\"><label for=\"vfb-1243\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1243\" id=\"vfb-1243\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1344\"><label for=\"vfb-1344\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1344\" id=\"vfb-1344\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1244\"><label for=\"vfb-1244\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1244\" id=\"vfb-1244\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1345\"><label for=\"vfb-1345\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1345\" id=\"vfb-1345\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1245\"><label for=\"vfb-1245\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1245\" id=\"vfb-1245\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1346\"><label for=\"vfb-1346\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1346\" id=\"vfb-1346\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1246\"><label for=\"vfb-1246\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1246\" id=\"vfb-1246\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1347\"><label for=\"vfb-1347\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1347\" id=\"vfb-1347\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1247\"><label for=\"vfb-1247\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1247\" id=\"vfb-1247\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1348\"><label for=\"vfb-1348\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1348\" id=\"vfb-1348\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1248\"><label for=\"vfb-1248\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1248\" id=\"vfb-1248\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1349\"><label for=\"vfb-1349\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1349\" id=\"vfb-1349\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1249\"><label for=\"vfb-1249\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1249\" id=\"vfb-1249\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1350\"><label for=\"vfb-1350\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1350\" id=\"vfb-1350\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1250\"><label for=\"vfb-1250\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1250\" id=\"vfb-1250\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1251\"><label for=\"vfb-1251\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1251\" id=\"vfb-1251\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1252\"><label for=\"vfb-1252\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1252\" id=\"vfb-1252\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1253\"><label for=\"vfb-1253\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1253\" id=\"vfb-1253\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1254\"><label for=\"vfb-1254\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1254\" id=\"vfb-1254\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1255\"><label for=\"vfb-1255\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1255\" id=\"vfb-1255\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1256\"><label for=\"vfb-1256\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1256\" id=\"vfb-1256\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1257\"><label for=\"vfb-1257\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1257\" id=\"vfb-1257\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1258\"><label for=\"vfb-1258\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1258\" id=\"vfb-1258\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1259\"><label for=\"vfb-1259\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1259\" id=\"vfb-1259\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1260\"><label for=\"vfb-1260\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1260\" id=\"vfb-1260\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1261\"><label for=\"vfb-1261\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1261\" id=\"vfb-1261\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1262\"><label for=\"vfb-1262\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1262\" id=\"vfb-1262\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1263\"><label for=\"vfb-1263\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1263\" id=\"vfb-1263\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1264\"><label for=\"vfb-1264\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1264\" id=\"vfb-1264\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1265\"><label for=\"vfb-1265\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1265\" id=\"vfb-1265\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1266\"><label for=\"vfb-1266\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1266\" id=\"vfb-1266\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1267\"><label for=\"vfb-1267\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1267\" id=\"vfb-1267\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1268\"><label for=\"vfb-1268\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1268\" id=\"vfb-1268\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1269\"><label for=\"vfb-1269\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1269\" id=\"vfb-1269\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1270\"><label for=\"vfb-1270\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1270\" id=\"vfb-1270\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1271\"><label for=\"vfb-1271\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1271\" id=\"vfb-1271\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1272\"><label for=\"vfb-1272\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1272\" id=\"vfb-1272\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1273\"><label for=\"vfb-1273\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1273\" id=\"vfb-1273\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1274\"><label for=\"vfb-1274\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1274\" id=\"vfb-1274\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1275\"><label for=\"vfb-1275\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1275\" id=\"vfb-1275\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1276\"><label for=\"vfb-1276\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1276\" id=\"vfb-1276\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1277\"><label for=\"vfb-1277\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1277\" id=\"vfb-1277\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1278\"><label for=\"vfb-1278\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1278\" id=\"vfb-1278\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1279\"><label for=\"vfb-1279\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1279\" id=\"vfb-1279\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1280\"><label for=\"vfb-1280\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1280\" id=\"vfb-1280\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1281\"><label for=\"vfb-1281\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1281\" id=\"vfb-1281\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1282\"><label for=\"vfb-1282\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1282\" id=\"vfb-1282\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1283\"><label for=\"vfb-1283\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1283\" id=\"vfb-1283\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1284\"><label for=\"vfb-1284\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1284\" id=\"vfb-1284\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1285\"><label for=\"vfb-1285\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1285\" id=\"vfb-1285\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1286\"><label for=\"vfb-1286\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1286\" id=\"vfb-1286\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1287\"><label for=\"vfb-1287\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1287\" id=\"vfb-1287\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1187\"><label for=\"vfb-1187\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1187\" id=\"vfb-1187\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1288\"><label for=\"vfb-1288\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1288\" id=\"vfb-1288\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1188\"><label for=\"vfb-1188\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1188\" id=\"vfb-1188\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1289\"><label for=\"vfb-1289\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1289\" id=\"vfb-1289\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1189\"><label for=\"vfb-1189\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1189\" id=\"vfb-1189\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1290\"><label for=\"vfb-1290\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1290\" id=\"vfb-1290\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1190\"><label for=\"vfb-1190\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1190\" id=\"vfb-1190\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1291\"><label for=\"vfb-1291\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1291\" id=\"vfb-1291\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1191\"><label for=\"vfb-1191\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1191\" id=\"vfb-1191\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1292\"><label for=\"vfb-1292\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1292\" id=\"vfb-1292\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1192\"><label for=\"vfb-1192\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1192\" id=\"vfb-1192\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1293\"><label for=\"vfb-1293\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1293\" id=\"vfb-1293\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1193\"><label for=\"vfb-1193\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1193\" id=\"vfb-1193\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1294\"><label for=\"vfb-1294\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1294\" id=\"vfb-1294\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1194\"><label for=\"vfb-1194\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1194\" id=\"vfb-1194\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1295\"><label for=\"vfb-1295\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1295\" id=\"vfb-1295\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1195\"><label for=\"vfb-1195\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1195\" id=\"vfb-1195\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1296\"><label for=\"vfb-1296\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1296\" id=\"vfb-1296\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1196\"><label for=\"vfb-1196\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1196\" id=\"vfb-1196\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1297\"><label for=\"vfb-1297\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1297\" id=\"vfb-1297\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1197\"><label for=\"vfb-1197\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1197\" id=\"vfb-1197\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1298\"><label for=\"vfb-1298\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1298\" id=\"vfb-1298\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1198\"><label for=\"vfb-1198\" class=\"vfb-desc\">Funktion <\/label><input type=\"text\" name=\"vfb-1198\" id=\"vfb-1198\" value=\"\" class=\"vfb-text  vfb-medium    funktion\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1299\"><label for=\"vfb-1299\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1299\" id=\"vfb-1299\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><li class=\"vfb-item vfb-item-text  \" id=\"item-vfb-1199\"><label for=\"vfb-1199\" class=\"vfb-desc\">Vorname Nachname <\/label><input type=\"text\" name=\"vfb-1199\" id=\"vfb-1199\" value=\"\" class=\"vfb-text  vfb-medium    name\" \/><\/li><\/ul>&nbsp;<\/fieldset><fieldset class=\"vfb-fieldset vfb-verification\" style=\"display:block\">\n\t\t\t\t<div class=\"vfb-legend\"><h3>Verification<\/h3><\/div>\n\t\t\t\t<ul class=\"vfb-section vfb-section-2\">\n\t\t\t\t<li class=\"vfb-item vfb-item-text\" style=\"display:block\">\n\t\t\t\t<label for=\"vfb-secret\" class=\"vfb-desc\">Please enter any two digits with &lt;strong&gt;no&lt;\/strong&gt; spaces (Example: 12)<span>*<\/span><\/label>\n\t\t\t\t<div><input type=\"text\" name=\"vfb-secret\" id=\"vfb-secret\" class=\"vfb-text vfb-medium\" style=\"display:block\" \/><\/div>\n\t\t\t\t<\/li><li style=\"display:none;\"><label>This box is for spam protection - &lt;strong&gt;please leave it blank&lt;\/strong&gt;:<\/label><div><input name=\"vfb-spam\" \/><\/div><\/li>\n\t\t\tSubmit<\/ul>\n\t\t\t<\/fieldset><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/blog\/wp-json\/wp\/v2\/posts\/8321\" \/><\/form><\/div> <!-- .visual-form-builder-container -->\n","protected":false},"excerpt":{"rendered":"<p>Neuromarketing in der Praxis Wie physische R\u00e4ume im digitalen Zeitalter gewinnbringend genutzt werden k\u00f6nnen. Mit dem Einzug der Digitalisierung hat sich ein grosser Teil der Gesch\u00e4ftsabschl\u00fcsse in den digitalen Raum verlagert. Es besteht f\u00fcr den Kunden oft keine absolute Notwenigkeit mehr, f\u00fcr einen Kauf den Weg in eine Filiale auf sich zu nehmen. Doch physische [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[290],"tags":[],"class_list":["post-8321","post","type-post","status-publish","format-standard","hentry","category-angebot"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NeuroBranches - ZUTT &amp; PARTNER AG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zutt.ch\/blog\/de\/neurobranches\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NeuroBranches - ZUTT &amp; PARTNER AG\" \/>\n<meta property=\"og:description\" content=\"Neuromarketing in der Praxis Wie physische R\u00e4ume im digitalen Zeitalter gewinnbringend genutzt werden k\u00f6nnen. Mit dem Einzug der Digitalisierung hat sich ein grosser Teil der Gesch\u00e4ftsabschl\u00fcsse in den digitalen Raum verlagert. Es besteht f\u00fcr den Kunden oft keine absolute Notwenigkeit mehr, f\u00fcr einen Kauf den Weg in eine Filiale auf sich zu nehmen. Doch physische [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zutt.ch\/blog\/de\/neurobranches\/\" \/>\n<meta property=\"og:site_name\" content=\"ZUTT &amp; PARTNER AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GlobalEmotionsForum\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-08T14:00:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-17T12:13:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2020\/09\/zutt-neuromarketing-raiffeisen-filiale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2409\" \/>\n\t<meta property=\"og:image:height\" content=\"1703\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"donato\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"donato\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/neurobranches\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/neurobranches\\\/\"},\"author\":{\"name\":\"donato\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#\\\/schema\\\/person\\\/04da9b282aefb5dee11f59956a986313\"},\"headline\":\"NeuroBranches\",\"datePublished\":\"2020-06-08T14:00:49+00:00\",\"dateModified\":\"2020-09-17T12:13:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/neurobranches\\\/\"},\"wordCount\":448,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/neurobranches\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/zutt-neuromarketing-Wert3.svg\",\"articleSection\":[\"Angebot\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/neurobranches\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/neurobranches\\\/\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/neurobranches\\\/\",\"name\":\"NeuroBranches - ZUTT &amp; PARTNER AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/neurobranches\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/neurobranches\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/zutt-neuromarketing-Wert3.svg\",\"datePublished\":\"2020-06-08T14:00:49+00:00\",\"dateModified\":\"2020-09-17T12:13:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/neurobranches\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/neurobranches\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/neurobranches\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/zutt-neuromarketing-Wert3.svg\",\"contentUrl\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/zutt-neuromarketing-Wert3.svg\",\"caption\":\"zutt-neuromarketing-Wert3\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/neurobranches\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NeuroBranches\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/\",\"name\":\"ZUTT &amp; PARTNER AG\",\"description\":\"Navigate Emotions\",\"publisher\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#organization\",\"name\":\"ZUTT & PARTNER AG\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Zutt-Partner-Logo.svg\",\"contentUrl\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Zutt-Partner-Logo.svg\",\"width\":1,\"height\":1,\"caption\":\"ZUTT & PARTNER AG\"},\"image\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GlobalEmotionsForum\",\"http:\\\/\\\/ch.linkedin.com\\\/company\\\/globalemotionsforum?trk=ppro_cprof\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#\\\/schema\\\/person\\\/04da9b282aefb5dee11f59956a986313\",\"name\":\"donato\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1e16c97acc3957ff09cf7bd45492bcadf8a74cd76b85718df3e910bcf5d4a1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1e16c97acc3957ff09cf7bd45492bcadf8a74cd76b85718df3e910bcf5d4a1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4f1e16c97acc3957ff09cf7bd45492bcadf8a74cd76b85718df3e910bcf5d4a1?s=96&d=mm&r=g\",\"caption\":\"donato\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NeuroBranches - ZUTT &amp; PARTNER AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zutt.ch\/blog\/de\/neurobranches\/","og_locale":"de_DE","og_type":"article","og_title":"NeuroBranches - ZUTT &amp; PARTNER AG","og_description":"Neuromarketing in der Praxis Wie physische R\u00e4ume im digitalen Zeitalter gewinnbringend genutzt werden k\u00f6nnen. Mit dem Einzug der Digitalisierung hat sich ein grosser Teil der Gesch\u00e4ftsabschl\u00fcsse in den digitalen Raum verlagert. Es besteht f\u00fcr den Kunden oft keine absolute Notwenigkeit mehr, f\u00fcr einen Kauf den Weg in eine Filiale auf sich zu nehmen. Doch physische [&hellip;]","og_url":"https:\/\/zutt.ch\/blog\/de\/neurobranches\/","og_site_name":"ZUTT &amp; PARTNER AG","article_publisher":"https:\/\/www.facebook.com\/GlobalEmotionsForum","article_published_time":"2020-06-08T14:00:49+00:00","article_modified_time":"2020-09-17T12:13:07+00:00","og_image":[{"width":2409,"height":1703,"url":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2020\/09\/zutt-neuromarketing-raiffeisen-filiale.jpg","type":"image\/jpeg"}],"author":"donato","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"donato","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zutt.ch\/blog\/de\/neurobranches\/#article","isPartOf":{"@id":"https:\/\/zutt.ch\/blog\/de\/neurobranches\/"},"author":{"name":"donato","@id":"https:\/\/zutt.ch\/blog\/#\/schema\/person\/04da9b282aefb5dee11f59956a986313"},"headline":"NeuroBranches","datePublished":"2020-06-08T14:00:49+00:00","dateModified":"2020-09-17T12:13:07+00:00","mainEntityOfPage":{"@id":"https:\/\/zutt.ch\/blog\/de\/neurobranches\/"},"wordCount":448,"commentCount":0,"publisher":{"@id":"https:\/\/zutt.ch\/blog\/#organization"},"image":{"@id":"https:\/\/zutt.ch\/blog\/de\/neurobranches\/#primaryimage"},"thumbnailUrl":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/04\/zutt-neuromarketing-Wert3.svg","articleSection":["Angebot"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zutt.ch\/blog\/de\/neurobranches\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zutt.ch\/blog\/de\/neurobranches\/","url":"https:\/\/zutt.ch\/blog\/de\/neurobranches\/","name":"NeuroBranches - ZUTT &amp; PARTNER AG","isPartOf":{"@id":"https:\/\/zutt.ch\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zutt.ch\/blog\/de\/neurobranches\/#primaryimage"},"image":{"@id":"https:\/\/zutt.ch\/blog\/de\/neurobranches\/#primaryimage"},"thumbnailUrl":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/04\/zutt-neuromarketing-Wert3.svg","datePublished":"2020-06-08T14:00:49+00:00","dateModified":"2020-09-17T12:13:07+00:00","breadcrumb":{"@id":"https:\/\/zutt.ch\/blog\/de\/neurobranches\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zutt.ch\/blog\/de\/neurobranches\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zutt.ch\/blog\/de\/neurobranches\/#primaryimage","url":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/04\/zutt-neuromarketing-Wert3.svg","contentUrl":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/04\/zutt-neuromarketing-Wert3.svg","caption":"zutt-neuromarketing-Wert3"},{"@type":"BreadcrumbList","@id":"https:\/\/zutt.ch\/blog\/de\/neurobranches\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zutt.ch\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"NeuroBranches"}]},{"@type":"WebSite","@id":"https:\/\/zutt.ch\/blog\/#website","url":"https:\/\/zutt.ch\/blog\/","name":"ZUTT &amp; PARTNER AG","description":"Navigate Emotions","publisher":{"@id":"https:\/\/zutt.ch\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zutt.ch\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/zutt.ch\/blog\/#organization","name":"ZUTT & PARTNER AG","url":"https:\/\/zutt.ch\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zutt.ch\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/03\/Zutt-Partner-Logo.svg","contentUrl":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/03\/Zutt-Partner-Logo.svg","width":1,"height":1,"caption":"ZUTT & PARTNER AG"},"image":{"@id":"https:\/\/zutt.ch\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GlobalEmotionsForum","http:\/\/ch.linkedin.com\/company\/globalemotionsforum?trk=ppro_cprof"]},{"@type":"Person","@id":"https:\/\/zutt.ch\/blog\/#\/schema\/person\/04da9b282aefb5dee11f59956a986313","name":"donato","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/4f1e16c97acc3957ff09cf7bd45492bcadf8a74cd76b85718df3e910bcf5d4a1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4f1e16c97acc3957ff09cf7bd45492bcadf8a74cd76b85718df3e910bcf5d4a1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4f1e16c97acc3957ff09cf7bd45492bcadf8a74cd76b85718df3e910bcf5d4a1?s=96&d=mm&r=g","caption":"donato"}}]}},"_links":{"self":[{"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/posts\/8321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/comments?post=8321"}],"version-history":[{"count":17,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/posts\/8321\/revisions"}],"predecessor-version":[{"id":8955,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/posts\/8321\/revisions\/8955"}],"wp:attachment":[{"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/media?parent=8321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/categories?post=8321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/tags?post=8321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}