{"id":12401,"date":"2023-11-03T09:02:59","date_gmt":"2023-11-03T09:02:59","guid":{"rendered":"https:\/\/zutt.ch\/?p=12401"},"modified":"2023-11-03T09:07:11","modified_gmt":"2023-11-03T09:07:11","slug":"beitrag-kosmetik","status":"publish","type":"post","link":"https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/","title":{"rendered":"Was Verpackungen m\u00e4nnlich macht"},"content":{"rendered":"<p>Schwarz oder grau, klare Formen und aufmerksamkeitsstarke Schriften dominieren auch weiterhin die Verpackungen f\u00fcr M\u00e4nnerkosmetik. Doch warum ist das so?<\/p>\n<p>Genau \u00fcber dieses Thema habe ich mich mit <a href=\"https:\/\/www.kosmetik-international.de\/\">KOSMETIK international<\/a> unterhalten und Erkl\u00e4rungen geliefert.<\/p>\n<p>Erfahren Sie im Beitrag, welche Gr\u00fcnde hinter diesem bew\u00e4hrten Schema stehen und wie es die Wahrnehmung von M\u00e4nnerkosmetik beeinflusst:<\/p>\n<p><a href=\"https:\/\/hosting.zutt.ch\/kosmetik-international-was-verpackungen-maennlich-macht.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-12403 size-large\" src=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/11\/zutt-neuromarketing-verpackungen-1024x570.jpg\" alt=\"\" width=\"640\" height=\"356\" srcset=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/11\/zutt-neuromarketing-verpackungen-1024x570.jpg 1024w, https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/11\/zutt-neuromarketing-verpackungen-300x167.jpg 300w, https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/11\/zutt-neuromarketing-verpackungen-768x427.jpg 768w, https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/11\/zutt-neuromarketing-verpackungen-1536x855.jpg 1536w, https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/11\/zutt-neuromarketing-verpackungen-2048x1140.jpg 2048w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/a><\/p>\n<p><span class=\"zuttbutton\" style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"https:\/\/hosting.zutt.ch\/kosmetik-international-was-verpackungen-maennlich-macht.pdf\" target=\"_blank\" rel=\"noopener\">&gt; Beitrag lesen<\/a><\/span><\/p>\n<p>M\u00f6chten Sie sich zu diesem Beitrag oder zu anderen wertvollen Neuro-Tipps mal telefonisch austauschen? Mehr Infos und ein unverbindliches Kontaktformular gibt&#8217;s hier:<br \/>\n<span class=\"zuttbutton\" style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"https:\/\/zutt.ch\/blog\/de\/workshop-seite\/\" target=\"_blank\" rel=\"noopener\">&gt; Kontakt aufnehmen<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schwarz oder grau, klare Formen und aufmerksamkeitsstarke Schriften dominieren auch weiterhin die Verpackungen f\u00fcr M\u00e4nnerkosmetik. Doch warum ist das so? Genau \u00fcber dieses Thema habe ich mich mit KOSMETIK international unterhalten und Erkl\u00e4rungen geliefert. Erfahren Sie im Beitrag, welche Gr\u00fcnde hinter diesem bew\u00e4hrten Schema stehen und wie es die Wahrnehmung von M\u00e4nnerkosmetik beeinflusst: &gt; Beitrag [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":12403,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[272],"tags":[],"class_list":["post-12401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Was Verpackungen m\u00e4nnlich macht | ZUTT &amp; PARTNERS<\/title>\n<meta name=\"description\" content=\"Schwarz oder grau, klare Formen und aufmerksamkeitsstarke Schriften dominieren auch weiterhin die Verpackungen f\u00fcr M\u00e4nnerkosmetik.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Was Verpackungen m\u00e4nnlich macht | ZUTT &amp; PARTNERS\" \/>\n<meta property=\"og:description\" content=\"Schwarz oder grau, klare Formen und aufmerksamkeitsstarke Schriften dominieren auch weiterhin die Verpackungen f\u00fcr M\u00e4nnerkosmetik.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/\" \/>\n<meta property=\"og:site_name\" content=\"ZUTT &amp; PARTNER AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GlobalEmotionsForum\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-03T09:02:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-03T09:07:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/11\/zutt-neuromarketing-verpackungen-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1424\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"zutt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"zutt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/beitrag-kosmetik\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/beitrag-kosmetik\\\/\"},\"author\":{\"name\":\"zutt\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#\\\/schema\\\/person\\\/5623224fe38fc82c0752ec8d4da2d5e8\"},\"headline\":\"Was Verpackungen m\u00e4nnlich macht\",\"datePublished\":\"2023-11-03T09:02:59+00:00\",\"dateModified\":\"2023-11-03T09:07:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/beitrag-kosmetik\\\/\"},\"wordCount\":94,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/beitrag-kosmetik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/zutt-neuromarketing-verpackungen-scaled.jpg\",\"articleSection\":[\"news\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/beitrag-kosmetik\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/beitrag-kosmetik\\\/\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/beitrag-kosmetik\\\/\",\"name\":\"Was Verpackungen m\u00e4nnlich macht | ZUTT & PARTNERS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/beitrag-kosmetik\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/beitrag-kosmetik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/zutt-neuromarketing-verpackungen-scaled.jpg\",\"datePublished\":\"2023-11-03T09:02:59+00:00\",\"dateModified\":\"2023-11-03T09:07:11+00:00\",\"description\":\"Schwarz oder grau, klare Formen und aufmerksamkeitsstarke Schriften dominieren auch weiterhin die Verpackungen f\u00fcr M\u00e4nnerkosmetik.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/beitrag-kosmetik\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/beitrag-kosmetik\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/beitrag-kosmetik\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/zutt-neuromarketing-verpackungen-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/zutt-neuromarketing-verpackungen-scaled.jpg\",\"width\":2560,\"height\":1424},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/beitrag-kosmetik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Was Verpackungen m\u00e4nnlich macht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/\",\"name\":\"ZUTT &amp; PARTNER AG\",\"description\":\"Navigate Emotions\",\"publisher\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#organization\",\"name\":\"ZUTT & PARTNER AG\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Zutt-Partner-Logo.svg\",\"contentUrl\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Zutt-Partner-Logo.svg\",\"width\":1,\"height\":1,\"caption\":\"ZUTT & PARTNER AG\"},\"image\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GlobalEmotionsForum\",\"http:\\\/\\\/ch.linkedin.com\\\/company\\\/globalemotionsforum?trk=ppro_cprof\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#\\\/schema\\\/person\\\/5623224fe38fc82c0752ec8d4da2d5e8\",\"name\":\"zutt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c307dbc804f8981d76e467bef83be31923815bf99b94eb64b34060f74dcac7b2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c307dbc804f8981d76e467bef83be31923815bf99b94eb64b34060f74dcac7b2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c307dbc804f8981d76e467bef83be31923815bf99b94eb64b34060f74dcac7b2?s=96&d=mm&r=g\",\"caption\":\"zutt\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Was Verpackungen m\u00e4nnlich macht | ZUTT & PARTNERS","description":"Schwarz oder grau, klare Formen und aufmerksamkeitsstarke Schriften dominieren auch weiterhin die Verpackungen f\u00fcr M\u00e4nnerkosmetik.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/","og_locale":"de_DE","og_type":"article","og_title":"Was Verpackungen m\u00e4nnlich macht | ZUTT & PARTNERS","og_description":"Schwarz oder grau, klare Formen und aufmerksamkeitsstarke Schriften dominieren auch weiterhin die Verpackungen f\u00fcr M\u00e4nnerkosmetik.","og_url":"https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/","og_site_name":"ZUTT &amp; PARTNER AG","article_publisher":"https:\/\/www.facebook.com\/GlobalEmotionsForum","article_published_time":"2023-11-03T09:02:59+00:00","article_modified_time":"2023-11-03T09:07:11+00:00","og_image":[{"width":2560,"height":1424,"url":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/11\/zutt-neuromarketing-verpackungen-scaled.jpg","type":"image\/jpeg"}],"author":"zutt","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"zutt","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/#article","isPartOf":{"@id":"https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/"},"author":{"name":"zutt","@id":"https:\/\/zutt.ch\/blog\/#\/schema\/person\/5623224fe38fc82c0752ec8d4da2d5e8"},"headline":"Was Verpackungen m\u00e4nnlich macht","datePublished":"2023-11-03T09:02:59+00:00","dateModified":"2023-11-03T09:07:11+00:00","mainEntityOfPage":{"@id":"https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/"},"wordCount":94,"commentCount":0,"publisher":{"@id":"https:\/\/zutt.ch\/blog\/#organization"},"image":{"@id":"https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/#primaryimage"},"thumbnailUrl":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/11\/zutt-neuromarketing-verpackungen-scaled.jpg","articleSection":["news"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/","url":"https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/","name":"Was Verpackungen m\u00e4nnlich macht | ZUTT & PARTNERS","isPartOf":{"@id":"https:\/\/zutt.ch\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/#primaryimage"},"image":{"@id":"https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/#primaryimage"},"thumbnailUrl":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/11\/zutt-neuromarketing-verpackungen-scaled.jpg","datePublished":"2023-11-03T09:02:59+00:00","dateModified":"2023-11-03T09:07:11+00:00","description":"Schwarz oder grau, klare Formen und aufmerksamkeitsstarke Schriften dominieren auch weiterhin die Verpackungen f\u00fcr M\u00e4nnerkosmetik.","breadcrumb":{"@id":"https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/#primaryimage","url":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/11\/zutt-neuromarketing-verpackungen-scaled.jpg","contentUrl":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/11\/zutt-neuromarketing-verpackungen-scaled.jpg","width":2560,"height":1424},{"@type":"BreadcrumbList","@id":"https:\/\/zutt.ch\/blog\/de\/beitrag-kosmetik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zutt.ch\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"Was Verpackungen m\u00e4nnlich macht"}]},{"@type":"WebSite","@id":"https:\/\/zutt.ch\/blog\/#website","url":"https:\/\/zutt.ch\/blog\/","name":"ZUTT &amp; PARTNER AG","description":"Navigate Emotions","publisher":{"@id":"https:\/\/zutt.ch\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zutt.ch\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/zutt.ch\/blog\/#organization","name":"ZUTT & PARTNER AG","url":"https:\/\/zutt.ch\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zutt.ch\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/03\/Zutt-Partner-Logo.svg","contentUrl":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/03\/Zutt-Partner-Logo.svg","width":1,"height":1,"caption":"ZUTT & PARTNER AG"},"image":{"@id":"https:\/\/zutt.ch\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GlobalEmotionsForum","http:\/\/ch.linkedin.com\/company\/globalemotionsforum?trk=ppro_cprof"]},{"@type":"Person","@id":"https:\/\/zutt.ch\/blog\/#\/schema\/person\/5623224fe38fc82c0752ec8d4da2d5e8","name":"zutt","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c307dbc804f8981d76e467bef83be31923815bf99b94eb64b34060f74dcac7b2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c307dbc804f8981d76e467bef83be31923815bf99b94eb64b34060f74dcac7b2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c307dbc804f8981d76e467bef83be31923815bf99b94eb64b34060f74dcac7b2?s=96&d=mm&r=g","caption":"zutt"}}]}},"_links":{"self":[{"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/posts\/12401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/comments?post=12401"}],"version-history":[{"count":4,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/posts\/12401\/revisions"}],"predecessor-version":[{"id":12407,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/posts\/12401\/revisions\/12407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/media\/12403"}],"wp:attachment":[{"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/media?parent=12401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/categories?post=12401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/tags?post=12401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}