{"id":11844,"date":"2023-07-06T06:26:16","date_gmt":"2023-07-06T06:26:16","guid":{"rendered":"https:\/\/zutt.ch\/?p=11844"},"modified":"2023-07-06T06:26:16","modified_gmt":"2023-07-06T06:26:16","slug":"radio-top-interview-uhrenzeiger","status":"publish","type":"post","link":"https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/","title":{"rendered":"Radio Top-Interview zu verschiedenen Neuromarketing-Effekten"},"content":{"rendered":"<p>Beim Blick in ein Schaufenster, in dem analoge Uhren ausgestellt sind, f\u00e4llt oft Eines auf: Auf allen Zifferbl\u00e4ttern ist&#8217;s 10 nach 10.<\/p>\n<p>Aber was hat es mit dieser Zeigerposition auf sich, die sich verschiedenste Marken von Nische bis Luxus zu Nutze machen?<\/p>\n<p>Dies und mehr erkl\u00e4rt Philipp Zutt in seinem Neuro-Tipp-Interview mit Radio Top:<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/UO2D7OaQ6ow\" width=\"800\" height=\"450\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n<p>M\u00f6chten Sie sich zu diesem Interview oder zu anderen wertvollen Neuro-Tipps mal telefonisch austauschen? Mehr Infos und ein unverbindliches Kontaktformular gibt&#8217;s hier:<br \/>\n<span class=\"zuttbutton\" style=\"color: #ffffff;\"><a style=\"color: #ffffff;\" href=\"https:\/\/zutt.ch\/blog\/de\/workshop-seite\/\" target=\"_blank\" rel=\"noopener\">&gt; Kontakt aufnehmen<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beim Blick in ein Schaufenster, in dem analoge Uhren ausgestellt sind, f\u00e4llt oft Eines auf: Auf allen Zifferbl\u00e4ttern ist&#8217;s 10 nach 10. Aber was hat es mit dieser Zeigerposition auf sich, die sich verschiedenste Marken von Nische bis Luxus zu Nutze machen? Dies und mehr erkl\u00e4rt Philipp Zutt in seinem Neuro-Tipp-Interview mit Radio Top: \ufeff [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":11843,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[272],"tags":[],"class_list":["post-11844","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Radio Top-Interview Uhrenzeiger 10 nach 10 | ZUTT &amp; PARTNERS<\/title>\n<meta name=\"description\" content=\"Wieso stehen die Zeiger von den meisten ausgestellten Uhren auf 10 nach 10?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Radio Top-Interview Uhrenzeiger 10 nach 10 | ZUTT &amp; PARTNERS\" \/>\n<meta property=\"og:description\" content=\"Wieso stehen die Zeiger von den meisten ausgestellten Uhren auf 10 nach 10?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/\" \/>\n<meta property=\"og:site_name\" content=\"ZUTT &amp; PARTNER AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GlobalEmotionsForum\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-06T06:26:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/05\/zutt-neuromarketing-radio-top-10nach10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"zutt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"zutt\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/radio-top-interview-uhrenzeiger\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/radio-top-interview-uhrenzeiger\\\/\"},\"author\":{\"name\":\"zutt\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#\\\/schema\\\/person\\\/5623224fe38fc82c0752ec8d4da2d5e8\"},\"headline\":\"Radio Top-Interview zu verschiedenen Neuromarketing-Effekten\",\"datePublished\":\"2023-07-06T06:26:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/radio-top-interview-uhrenzeiger\\\/\"},\"wordCount\":88,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/radio-top-interview-uhrenzeiger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/zutt-neuromarketing-radio-top-10nach10.jpg\",\"articleSection\":[\"news\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/radio-top-interview-uhrenzeiger\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/radio-top-interview-uhrenzeiger\\\/\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/radio-top-interview-uhrenzeiger\\\/\",\"name\":\"Radio Top-Interview Uhrenzeiger 10 nach 10 | ZUTT & PARTNERS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/radio-top-interview-uhrenzeiger\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/radio-top-interview-uhrenzeiger\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/zutt-neuromarketing-radio-top-10nach10.jpg\",\"datePublished\":\"2023-07-06T06:26:16+00:00\",\"description\":\"Wieso stehen die Zeiger von den meisten ausgestellten Uhren auf 10 nach 10?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/radio-top-interview-uhrenzeiger\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/radio-top-interview-uhrenzeiger\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/radio-top-interview-uhrenzeiger\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/zutt-neuromarketing-radio-top-10nach10.jpg\",\"contentUrl\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/zutt-neuromarketing-radio-top-10nach10.jpg\",\"width\":1200,\"height\":627},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/radio-top-interview-uhrenzeiger\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Radio Top-Interview zu verschiedenen Neuromarketing-Effekten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/\",\"name\":\"ZUTT &amp; PARTNER AG\",\"description\":\"Navigate Emotions\",\"publisher\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#organization\",\"name\":\"ZUTT & PARTNER AG\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Zutt-Partner-Logo.svg\",\"contentUrl\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Zutt-Partner-Logo.svg\",\"width\":1,\"height\":1,\"caption\":\"ZUTT & PARTNER AG\"},\"image\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GlobalEmotionsForum\",\"http:\\\/\\\/ch.linkedin.com\\\/company\\\/globalemotionsforum?trk=ppro_cprof\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#\\\/schema\\\/person\\\/5623224fe38fc82c0752ec8d4da2d5e8\",\"name\":\"zutt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c307dbc804f8981d76e467bef83be31923815bf99b94eb64b34060f74dcac7b2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c307dbc804f8981d76e467bef83be31923815bf99b94eb64b34060f74dcac7b2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c307dbc804f8981d76e467bef83be31923815bf99b94eb64b34060f74dcac7b2?s=96&d=mm&r=g\",\"caption\":\"zutt\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Radio Top-Interview Uhrenzeiger 10 nach 10 | ZUTT & PARTNERS","description":"Wieso stehen die Zeiger von den meisten ausgestellten Uhren auf 10 nach 10?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/","og_locale":"de_DE","og_type":"article","og_title":"Radio Top-Interview Uhrenzeiger 10 nach 10 | ZUTT & PARTNERS","og_description":"Wieso stehen die Zeiger von den meisten ausgestellten Uhren auf 10 nach 10?","og_url":"https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/","og_site_name":"ZUTT &amp; PARTNER AG","article_publisher":"https:\/\/www.facebook.com\/GlobalEmotionsForum","article_published_time":"2023-07-06T06:26:16+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/05\/zutt-neuromarketing-radio-top-10nach10.jpg","type":"image\/jpeg"}],"author":"zutt","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"zutt","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/#article","isPartOf":{"@id":"https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/"},"author":{"name":"zutt","@id":"https:\/\/zutt.ch\/blog\/#\/schema\/person\/5623224fe38fc82c0752ec8d4da2d5e8"},"headline":"Radio Top-Interview zu verschiedenen Neuromarketing-Effekten","datePublished":"2023-07-06T06:26:16+00:00","mainEntityOfPage":{"@id":"https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/"},"wordCount":88,"commentCount":0,"publisher":{"@id":"https:\/\/zutt.ch\/blog\/#organization"},"image":{"@id":"https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/#primaryimage"},"thumbnailUrl":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/05\/zutt-neuromarketing-radio-top-10nach10.jpg","articleSection":["news"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/","url":"https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/","name":"Radio Top-Interview Uhrenzeiger 10 nach 10 | ZUTT & PARTNERS","isPartOf":{"@id":"https:\/\/zutt.ch\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/#primaryimage"},"image":{"@id":"https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/#primaryimage"},"thumbnailUrl":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/05\/zutt-neuromarketing-radio-top-10nach10.jpg","datePublished":"2023-07-06T06:26:16+00:00","description":"Wieso stehen die Zeiger von den meisten ausgestellten Uhren auf 10 nach 10?","breadcrumb":{"@id":"https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/#primaryimage","url":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/05\/zutt-neuromarketing-radio-top-10nach10.jpg","contentUrl":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2023\/05\/zutt-neuromarketing-radio-top-10nach10.jpg","width":1200,"height":627},{"@type":"BreadcrumbList","@id":"https:\/\/zutt.ch\/blog\/de\/radio-top-interview-uhrenzeiger\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zutt.ch\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"Radio Top-Interview zu verschiedenen Neuromarketing-Effekten"}]},{"@type":"WebSite","@id":"https:\/\/zutt.ch\/blog\/#website","url":"https:\/\/zutt.ch\/blog\/","name":"ZUTT &amp; PARTNER AG","description":"Navigate Emotions","publisher":{"@id":"https:\/\/zutt.ch\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zutt.ch\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/zutt.ch\/blog\/#organization","name":"ZUTT & PARTNER AG","url":"https:\/\/zutt.ch\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zutt.ch\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/03\/Zutt-Partner-Logo.svg","contentUrl":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/03\/Zutt-Partner-Logo.svg","width":1,"height":1,"caption":"ZUTT & PARTNER AG"},"image":{"@id":"https:\/\/zutt.ch\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GlobalEmotionsForum","http:\/\/ch.linkedin.com\/company\/globalemotionsforum?trk=ppro_cprof"]},{"@type":"Person","@id":"https:\/\/zutt.ch\/blog\/#\/schema\/person\/5623224fe38fc82c0752ec8d4da2d5e8","name":"zutt","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/c307dbc804f8981d76e467bef83be31923815bf99b94eb64b34060f74dcac7b2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c307dbc804f8981d76e467bef83be31923815bf99b94eb64b34060f74dcac7b2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c307dbc804f8981d76e467bef83be31923815bf99b94eb64b34060f74dcac7b2?s=96&d=mm&r=g","caption":"zutt"}}]}},"_links":{"self":[{"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/posts\/11844","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/comments?post=11844"}],"version-history":[{"count":9,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/posts\/11844\/revisions"}],"predecessor-version":[{"id":11853,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/posts\/11844\/revisions\/11853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/media\/11843"}],"wp:attachment":[{"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/media?parent=11844"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/categories?post=11844"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/tags?post=11844"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}