{"id":10757,"date":"2023-01-26T13:41:39","date_gmt":"2023-01-26T13:41:39","guid":{"rendered":"https:\/\/zutt.smore.ch\/?p=10757"},"modified":"2025-09-18T16:12:12","modified_gmt":"2025-09-18T16:12:12","slug":"case-raiffeisen-schokolade","status":"publish","type":"post","link":"https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/","title":{"rendered":"Raffeisen: So werden Markenwerte schmeckbar"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5894\" src=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/04\/zutt-neuromarketing-Wert3.svg\" alt=\"zutt-neuromarketing-Anspruch\" width=\"99\" height=\"153\" \/><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #187477;\">1. ANSPRUCH<\/span><strong><br \/>\n<\/strong><\/strong>Die Raiffeisen Mittleres Toggenburg, ihre Beratung und die f\u00fcr den Kunden daraus resultierenden Benefits in eine emotional passende Schokoladen-Eigenkreation giessen.<\/p>\n<p style=\"margin-top: 75px;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5894\" src=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/04\/zutt-neuromarketing-Wert1.svg\" alt=\"zutt-neuromarketing-Insights\" width=\"99\" height=\"153\" \/><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #187477;\"><strong>2. INSIGHTS EMOCOMPASS\u00ae-STUDIE<\/strong><\/span><br \/>\n\u2022 Das Gesch\u00e4ftsstellen-Erlebnis l\u00e4sst sich Richtung GOLD STANDARD optimieren<br \/>\n\u2022 Das emotional treffende Ausspielen der Werte hilft dabei<br \/>\n\u2022 So k\u00f6nnen auch Mitbewerber abgeh\u00e4ngt werden<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5841 size-full\" src=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2019\/08\/zutt-neuromarketing-raiffeisen-schokolade-taste.png\" alt=\"\" width=\"1024\" height=\"546\" \/><\/p>\n<p style=\"margin-top: -25px;\"><span style=\"color: #187477; font-size: 10pt; line-height: 0;\">EmoMap\u00a9: Es geht nicht um oben, unten, links oder rechts \u2013 massgebend sind die Abst\u00e4nde zwischen den einzelnen Research Objects zum Wunsch (GOLD STANDARD). Je weiter die Entfernung zwischen zwei Pins, desto unterschiedlicher die Empfindung.<\/span><\/p>\n<p style=\"margin-top: 75px;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-5894\" src=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/04\/zutt-neuromarketing-Wert2.svg\" alt=\"zutt-neuromarketing-emomap-raiffeisen-schokolade\" width=\"99\" height=\"153\" \/><br \/>\n<strong><span style=\"color: #187477;\">3. ENTWICKLUNG UND REZEPTUR-INPUTS INKL. BEGLEITKOMMUNIKATION<\/span><\/strong><br \/>\nVer\u00e4nderung des Gespr\u00e4chseinstiegs: Von einer klassischen Bankvorstellung hin zu einer multisensualen Erlebnis-Pr\u00e4sentation. Nicht der Berater erkl\u00e4rt dem Kunden, wof\u00fcr die Raiffeisen Mittleres Toggenburg steht, sondern die Kunden den Beratern \u2013 \u00fcber alle Sinne inspiriert und motiviert w\u00e4hrend des Schokoladen-Genusses. Die Botschaften der Bank werden so nachhaltig beim Kunden verankert. Ein lukrativer Nebeneffekt: Bestehende Kunden bringen Neukunden mit in die Gesch\u00e4ftsstelle \u2013 damit diese die Raiffeisen Schokolade probieren k\u00f6nnen. Die Raiffeisen Mittleres Toggenburg w\u00e4chst.<br \/>\n<img decoding=\"async\" class=\"aligncenter wp-image-5894\" src=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2019\/10\/zutt-partner-neuromarketing-raiffeisen-schokolade.png\" alt=\"Case Bild einer Raiffeisen Schokolade\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>1. ANSPRUCH Die Raiffeisen Mittleres Toggenburg, ihre Beratung und die f\u00fcr den Kunden daraus resultierenden Benefits in eine emotional passende Schokoladen-Eigenkreation giessen. 2. INSIGHTS EMOCOMPASS\u00ae-STUDIE \u2022 Das Gesch\u00e4ftsstellen-Erlebnis l\u00e4sst sich Richtung GOLD STANDARD optimieren \u2022 Das emotional treffende Ausspielen der Werte hilft dabei \u2022 So k\u00f6nnen auch Mitbewerber abgeh\u00e4ngt werden EmoMap\u00a9: Es geht nicht um [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":7200,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[317,331],"tags":[],"class_list":["post-10757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cases","category-taste"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Raffeisen: So werden Markenwerte schmeckbar<\/title>\n<meta name=\"description\" content=\"Die Raiffeisen Mittleres Toggenburg, ihre Beratung und die Benefits in eine emotional passende Schokoladen-Eigenkreation giessen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Raffeisen: So werden Markenwerte schmeckbar\" \/>\n<meta property=\"og:description\" content=\"Die Raiffeisen Mittleres Toggenburg, ihre Beratung und die Benefits in eine emotional passende Schokoladen-Eigenkreation giessen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/\" \/>\n<meta property=\"og:site_name\" content=\"ZUTT &amp; PARTNER AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GlobalEmotionsForum\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-26T13:41:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-18T16:12:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2019\/10\/zutt-partner-neuromarketing-raiffeisen-schokolade.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"915\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"leonhard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"leonhard\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/case-raiffeisen-schokolade\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/case-raiffeisen-schokolade\\\/\"},\"author\":{\"name\":\"leonhard\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#\\\/schema\\\/person\\\/470c7652e57943d6bc8918e267f034c9\"},\"headline\":\"Raffeisen: So werden Markenwerte schmeckbar\",\"datePublished\":\"2023-01-26T13:41:39+00:00\",\"dateModified\":\"2025-09-18T16:12:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/case-raiffeisen-schokolade\\\/\"},\"wordCount\":176,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/case-raiffeisen-schokolade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/zutt-partner-neuromarketing-raiffeisen-schokolade.png\",\"articleSection\":[\"cases\",\"NeuroTaste\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/case-raiffeisen-schokolade\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/case-raiffeisen-schokolade\\\/\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/case-raiffeisen-schokolade\\\/\",\"name\":\"Raffeisen: So werden Markenwerte schmeckbar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/case-raiffeisen-schokolade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/case-raiffeisen-schokolade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/zutt-partner-neuromarketing-raiffeisen-schokolade.png\",\"datePublished\":\"2023-01-26T13:41:39+00:00\",\"dateModified\":\"2025-09-18T16:12:12+00:00\",\"description\":\"Die Raiffeisen Mittleres Toggenburg, ihre Beratung und die Benefits in eine emotional passende Schokoladen-Eigenkreation giessen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/case-raiffeisen-schokolade\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/case-raiffeisen-schokolade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/case-raiffeisen-schokolade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/zutt-partner-neuromarketing-raiffeisen-schokolade.png\",\"contentUrl\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/zutt-partner-neuromarketing-raiffeisen-schokolade.png\",\"width\":1000,\"height\":915,\"caption\":\"Case Bild einer Raiffeisen Schokolade\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/case-raiffeisen-schokolade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Raffeisen: So werden Markenwerte schmeckbar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/\",\"name\":\"ZUTT &amp; PARTNER AG\",\"description\":\"Navigate Emotions\",\"publisher\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#organization\",\"name\":\"ZUTT & PARTNER AG\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Zutt-Partner-Logo.svg\",\"contentUrl\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/Zutt-Partner-Logo.svg\",\"width\":1,\"height\":1,\"caption\":\"ZUTT & PARTNER AG\"},\"image\":{\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GlobalEmotionsForum\",\"http:\\\/\\\/ch.linkedin.com\\\/company\\\/globalemotionsforum?trk=ppro_cprof\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zutt.ch\\\/blog\\\/#\\\/schema\\\/person\\\/470c7652e57943d6bc8918e267f034c9\",\"name\":\"leonhard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdf03b69ee18b7430d06b3c35513a1286b8d3c8a3700b3c88adb914652537b10?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdf03b69ee18b7430d06b3c35513a1286b8d3c8a3700b3c88adb914652537b10?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bdf03b69ee18b7430d06b3c35513a1286b8d3c8a3700b3c88adb914652537b10?s=96&d=mm&r=g\",\"caption\":\"leonhard\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Raffeisen: So werden Markenwerte schmeckbar","description":"Die Raiffeisen Mittleres Toggenburg, ihre Beratung und die Benefits in eine emotional passende Schokoladen-Eigenkreation giessen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/","og_locale":"de_DE","og_type":"article","og_title":"Raffeisen: So werden Markenwerte schmeckbar","og_description":"Die Raiffeisen Mittleres Toggenburg, ihre Beratung und die Benefits in eine emotional passende Schokoladen-Eigenkreation giessen.","og_url":"https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/","og_site_name":"ZUTT &amp; PARTNER AG","article_publisher":"https:\/\/www.facebook.com\/GlobalEmotionsForum","article_published_time":"2023-01-26T13:41:39+00:00","article_modified_time":"2025-09-18T16:12:12+00:00","og_image":[{"width":1000,"height":915,"url":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2019\/10\/zutt-partner-neuromarketing-raiffeisen-schokolade.png","type":"image\/png"}],"author":"leonhard","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"leonhard","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/#article","isPartOf":{"@id":"https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/"},"author":{"name":"leonhard","@id":"https:\/\/zutt.ch\/blog\/#\/schema\/person\/470c7652e57943d6bc8918e267f034c9"},"headline":"Raffeisen: So werden Markenwerte schmeckbar","datePublished":"2023-01-26T13:41:39+00:00","dateModified":"2025-09-18T16:12:12+00:00","mainEntityOfPage":{"@id":"https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/"},"wordCount":176,"commentCount":0,"publisher":{"@id":"https:\/\/zutt.ch\/blog\/#organization"},"image":{"@id":"https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/#primaryimage"},"thumbnailUrl":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2019\/10\/zutt-partner-neuromarketing-raiffeisen-schokolade.png","articleSection":["cases","NeuroTaste"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/","url":"https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/","name":"Raffeisen: So werden Markenwerte schmeckbar","isPartOf":{"@id":"https:\/\/zutt.ch\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/#primaryimage"},"image":{"@id":"https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/#primaryimage"},"thumbnailUrl":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2019\/10\/zutt-partner-neuromarketing-raiffeisen-schokolade.png","datePublished":"2023-01-26T13:41:39+00:00","dateModified":"2025-09-18T16:12:12+00:00","description":"Die Raiffeisen Mittleres Toggenburg, ihre Beratung und die Benefits in eine emotional passende Schokoladen-Eigenkreation giessen.","breadcrumb":{"@id":"https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/#primaryimage","url":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2019\/10\/zutt-partner-neuromarketing-raiffeisen-schokolade.png","contentUrl":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2019\/10\/zutt-partner-neuromarketing-raiffeisen-schokolade.png","width":1000,"height":915,"caption":"Case Bild einer Raiffeisen Schokolade"},{"@type":"BreadcrumbList","@id":"https:\/\/zutt.ch\/blog\/de\/case-raiffeisen-schokolade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zutt.ch\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"Raffeisen: So werden Markenwerte schmeckbar"}]},{"@type":"WebSite","@id":"https:\/\/zutt.ch\/blog\/#website","url":"https:\/\/zutt.ch\/blog\/","name":"ZUTT &amp; PARTNER AG","description":"Navigate Emotions","publisher":{"@id":"https:\/\/zutt.ch\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zutt.ch\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/zutt.ch\/blog\/#organization","name":"ZUTT & PARTNER AG","url":"https:\/\/zutt.ch\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zutt.ch\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/03\/Zutt-Partner-Logo.svg","contentUrl":"https:\/\/zutt.ch\/blog\/wp-content\/uploads\/2018\/03\/Zutt-Partner-Logo.svg","width":1,"height":1,"caption":"ZUTT & PARTNER AG"},"image":{"@id":"https:\/\/zutt.ch\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GlobalEmotionsForum","http:\/\/ch.linkedin.com\/company\/globalemotionsforum?trk=ppro_cprof"]},{"@type":"Person","@id":"https:\/\/zutt.ch\/blog\/#\/schema\/person\/470c7652e57943d6bc8918e267f034c9","name":"leonhard","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/bdf03b69ee18b7430d06b3c35513a1286b8d3c8a3700b3c88adb914652537b10?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bdf03b69ee18b7430d06b3c35513a1286b8d3c8a3700b3c88adb914652537b10?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bdf03b69ee18b7430d06b3c35513a1286b8d3c8a3700b3c88adb914652537b10?s=96&d=mm&r=g","caption":"leonhard"}}]}},"_links":{"self":[{"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/posts\/10757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/comments?post=10757"}],"version-history":[{"count":6,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/posts\/10757\/revisions"}],"predecessor-version":[{"id":15601,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/posts\/10757\/revisions\/15601"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/media\/7200"}],"wp:attachment":[{"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/media?parent=10757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/categories?post=10757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zutt.ch\/blog\/wp-json\/wp\/v2\/tags?post=10757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}